{"id":1529,"date":"2018-08-28T13:36:42","date_gmt":"2018-08-28T13:36:42","guid":{"rendered":"https:\/\/hotell.uhotelsgroup.com\/restoranemmeline\/events\/"},"modified":"2024-07-01T07:21:20","modified_gmt":"2024-07-01T07:21:20","slug":"uritused","status":"publish","type":"page","link":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/","title":{"rendered":"\u00dcritused"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":1546,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1529","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00dcritused - OTTO Restoran<\/title>\n<meta name=\"description\" content=\"Meeldej\u00e4\u00e4v s\u00fcnnip\u00e4ev v\u00f5i muu t\u00e4htp\u00e4ev organiseeri restoranis Emmeline &amp; Otto. Meie meeskond aitab korraldada sinu unistuste \u00fcrituse, loe rohkem kodulehelt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/\" \/>\n<meta property=\"og:locale\" content=\"et_EE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcritused - OTTO Restoran\" \/>\n<meta property=\"og:description\" content=\"Meeldej\u00e4\u00e4v s\u00fcnnip\u00e4ev v\u00f5i muu t\u00e4htp\u00e4ev organiseeri restoranis Emmeline &amp; Otto. Meie meeskond aitab korraldada sinu unistuste \u00fcrituse, loe rohkem kodulehelt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/\" \/>\n<meta property=\"og:site_name\" content=\"OTTO Restoran\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-01T07:21:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/\",\"url\":\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/\",\"name\":\"\u00dcritused - OTTO Restoran\",\"isPartOf\":{\"@id\":\"https:\/\/www.ottoresto.ee\/#website\"},\"datePublished\":\"2018-08-28T13:36:42+00:00\",\"dateModified\":\"2024-07-01T07:21:20+00:00\",\"description\":\"Meeldej\u00e4\u00e4v s\u00fcnnip\u00e4ev v\u00f5i muu t\u00e4htp\u00e4ev organiseeri restoranis Emmeline & Otto. Meie meeskond aitab korraldada sinu unistuste \u00fcrituse, loe rohkem kodulehelt.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/#breadcrumb\"},\"inLanguage\":\"et\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ottoresto.ee\/et\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pakkumised ja \u00fcritused\",\"item\":\"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00dcritused\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ottoresto.ee\/#website\",\"url\":\"https:\/\/www.ottoresto.ee\/\",\"name\":\"OTTO Restoran\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.ottoresto.ee\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ottoresto.ee\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"et\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ottoresto.ee\/#organization\",\"name\":\"OTTO Restoran\",\"url\":\"https:\/\/www.ottoresto.ee\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"et\",\"@id\":\"https:\/\/www.ottoresto.ee\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ottoresto.ee\/wp-content\/uploads\/sites\/9\/2023\/06\/cropped-OTTO-Restoran-Terrass-logo.png\",\"contentUrl\":\"https:\/\/www.ottoresto.ee\/wp-content\/uploads\/sites\/9\/2023\/06\/cropped-OTTO-Restoran-Terrass-logo.png\",\"width\":300,\"height\":283,\"caption\":\"OTTO Restoran\"},\"image\":{\"@id\":\"https:\/\/www.ottoresto.ee\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcritused - OTTO Restoran","description":"Meeldej\u00e4\u00e4v s\u00fcnnip\u00e4ev v\u00f5i muu t\u00e4htp\u00e4ev organiseeri restoranis Emmeline & Otto. Meie meeskond aitab korraldada sinu unistuste \u00fcrituse, loe rohkem kodulehelt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/","og_locale":"et_EE","og_type":"article","og_title":"\u00dcritused - OTTO Restoran","og_description":"Meeldej\u00e4\u00e4v s\u00fcnnip\u00e4ev v\u00f5i muu t\u00e4htp\u00e4ev organiseeri restoranis Emmeline & Otto. Meie meeskond aitab korraldada sinu unistuste \u00fcrituse, loe rohkem kodulehelt.","og_url":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/","og_site_name":"OTTO Restoran","article_modified_time":"2024-07-01T07:21:20+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/","url":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/","name":"\u00dcritused - OTTO Restoran","isPartOf":{"@id":"https:\/\/www.ottoresto.ee\/#website"},"datePublished":"2018-08-28T13:36:42+00:00","dateModified":"2024-07-01T07:21:20+00:00","description":"Meeldej\u00e4\u00e4v s\u00fcnnip\u00e4ev v\u00f5i muu t\u00e4htp\u00e4ev organiseeri restoranis Emmeline & Otto. Meie meeskond aitab korraldada sinu unistuste \u00fcrituse, loe rohkem kodulehelt.","breadcrumb":{"@id":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/#breadcrumb"},"inLanguage":"et","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/uritused\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ottoresto.ee\/et\/"},{"@type":"ListItem","position":2,"name":"Pakkumised ja \u00fcritused","item":"https:\/\/www.ottoresto.ee\/et\/pakkumised-ja-uritused\/"},{"@type":"ListItem","position":3,"name":"\u00dcritused"}]},{"@type":"WebSite","@id":"https:\/\/www.ottoresto.ee\/#website","url":"https:\/\/www.ottoresto.ee\/","name":"OTTO Restoran","description":"","publisher":{"@id":"https:\/\/www.ottoresto.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ottoresto.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"et"},{"@type":"Organization","@id":"https:\/\/www.ottoresto.ee\/#organization","name":"OTTO Restoran","url":"https:\/\/www.ottoresto.ee\/","logo":{"@type":"ImageObject","inLanguage":"et","@id":"https:\/\/www.ottoresto.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.ottoresto.ee\/wp-content\/uploads\/sites\/9\/2023\/06\/cropped-OTTO-Restoran-Terrass-logo.png","contentUrl":"https:\/\/www.ottoresto.ee\/wp-content\/uploads\/sites\/9\/2023\/06\/cropped-OTTO-Restoran-Terrass-logo.png","width":300,"height":283,"caption":"OTTO Restoran"},"image":{"@id":"https:\/\/www.ottoresto.ee\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/pages\/1529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/comments?post=1529"}],"version-history":[{"count":9,"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/pages\/1529\/revisions"}],"predecessor-version":[{"id":3806,"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/pages\/1529\/revisions\/3806"}],"up":[{"embeddable":true,"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/pages\/1546"}],"wp:attachment":[{"href":"https:\/\/www.ottoresto.ee\/et\/wp-json\/wp\/v2\/media?parent=1529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}